{"id":511,"count":7,"description":"","link":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/","name":"PT","slug":"pt","taxonomy":"product_cat","parent":378,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PT archivos - Megablok<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PT archivos - Megablok\" \/>\n<meta property=\"og:url\" content=\"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/\" \/>\n<meta property=\"og:site_name\" content=\"Megablok\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/megablok.com\\\/product-category\\\/taquillas-de-plastico\\\/pt\\\/\",\"url\":\"https:\\\/\\\/megablok.com\\\/product-category\\\/taquillas-de-plastico\\\/pt\\\/\",\"name\":\"PT archivos - Megablok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/megablok.com\\\/product-category\\\/taquillas-de-plastico\\\/pt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/megablok.com\\\/product-category\\\/taquillas-de-plastico\\\/pt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/megablok.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taquillas de pl\u00e1stico\",\"item\":\"https:\\\/\\\/megablok.com\\\/en\\\/product-category\\\/taquillas-de-plastico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/megablok.com\\\/en\\\/\",\"name\":\"Megablok\",\"description\":\"Taquillas para vestuarios de empresas y organizaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/megablok.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#organization\",\"name\":\"Megablok\",\"url\":\"https:\\\/\\\/megablok.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/megablok.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/270.png\",\"contentUrl\":\"https:\\\/\\\/megablok.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/270.png\",\"width\":270,\"height\":270,\"caption\":\"Megablok\"},\"image\":{\"@id\":\"https:\\\/\\\/megablok.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/megablok-s.a.\\\/\",\"https:\\\/\\\/www.instagram.com\\\/megabloksa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PT archivos - Megablok","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"PT archivos - Megablok","og_url":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/","og_site_name":"Megablok","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/","url":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/","name":"PT archivos - Megablok","isPartOf":{"@id":"https:\/\/megablok.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/megablok.com\/product-category\/taquillas-de-plastico\/pt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/megablok.com\/en\/"},{"@type":"ListItem","position":2,"name":"Taquillas de pl\u00e1stico","item":"https:\/\/megablok.com\/en\/product-category\/taquillas-de-plastico\/"},{"@type":"ListItem","position":3,"name":"PT"}]},{"@type":"WebSite","@id":"https:\/\/megablok.com\/en\/#website","url":"https:\/\/megablok.com\/en\/","name":"Megablok","description":"Taquillas para vestuarios de empresas y organizaciones","publisher":{"@id":"https:\/\/megablok.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/megablok.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/megablok.com\/en\/#organization","name":"Megablok","url":"https:\/\/megablok.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/megablok.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/megablok.com\/wp-content\/uploads\/2024\/08\/270.png","contentUrl":"https:\/\/megablok.com\/wp-content\/uploads\/2024\/08\/270.png","width":270,"height":270,"caption":"Megablok"},"image":{"@id":"https:\/\/megablok.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/megablok-s.a.\/","https:\/\/www.instagram.com\/megabloksa\/"]}]}},"_links":{"self":[{"href":"https:\/\/megablok.com\/en\/wp-json\/wp\/v2\/product_cat\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megablok.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/megablok.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/megablok.com\/en\/wp-json\/wp\/v2\/product_cat\/378"}],"wp:post_type":[{"href":"https:\/\/megablok.com\/en\/wp-json\/wp\/v2\/product?product_cat=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}